{"id":13366,"date":"2026-09-01T18:06:16","date_gmt":"2026-09-01T16:06:16","guid":{"rendered":"https:\/\/www.istruzione.calabria.it\/cosenza\/?p=13366"},"modified":"2026-09-01T18:06:26","modified_gmt":"2026-09-01T16:06:26","slug":"disponibilita-nomine-a-tempo-determinato-a-s-2026-2027","status":"publish","type":"post","link":"https:\/\/www.istruzione.calabria.it\/cosenza\/disponibilita-nomine-a-tempo-determinato-a-s-2026-2027\/","title":{"rendered":"Personale ATA &#8211; Pubblicazione disponibilit\u00e0 nomine a Tempo Determinato a.s. 2026-2027"},"content":{"rendered":"<!-- WP Attachments -->\r\n        <div class=\"wpa-attachments-block\">\r\n            <div class=\"wpa-attachments-head\">\r\n                <h3 class=\"wpa-attachments-title\">Allegati<\/h3>\r\n            <\/div>\r\n        <ul class=\"post-attachments\"><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-content\/uploads\/2026\/09\/m_pi.AOOUSPCS.REGISTRO-UFFICIALEU.0013060.01-09-2026.pdf\">m_pi.AOOUSPCS.REGISTRO UFFICIALE(U).0013060.01-09-2026<\/a> <small>(135 KB)<\/small><\/li><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-content\/uploads\/2026\/09\/Disponibilita-per-nomine-a-tempo-determinato.pdf\">Disponibilit\u00e0 per nomine a tempo determinato<\/a> <small>(98 KB)<\/small><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Allegati m_pi.AOOUSPCS.REGISTRO UFFICIALE(U).0013060.01-09-2026 (135 KB)Disponibilit\u00e0 per nomine a tempo determinato (98 KB)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[74,112,88,77],"tags":[],"class_list":["post-13366","post","type-post","status-publish","format-standard","hentry","category-ata","category-albo-atti-correnti","category-an","category-cn"],"_links":{"self":[{"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/posts\/13366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/comments?post=13366"}],"version-history":[{"count":1,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/posts\/13366\/revisions"}],"predecessor-version":[{"id":13369,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/posts\/13366\/revisions\/13369"}],"wp:attachment":[{"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/media?parent=13366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/categories?post=13366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.istruzione.calabria.it\/cosenza\/wp-json\/wp\/v2\/tags?post=13366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}